{"id":12002,"date":"2022-08-21T18:07:07","date_gmt":"2022-08-21T18:07:07","guid":{"rendered":"https:\/\/standardsmagazine.com\/?p=12002"},"modified":"2022-08-22T07:09:39","modified_gmt":"2022-08-22T07:09:39","slug":"the-perfect-duo-for-the-most-gentle-shower-time","status":"publish","type":"post","link":"https:\/\/standardsmagazine.com\/en\/the-perfect-duo-for-the-most-gentle-shower-time\/","title":{"rendered":"The perfect duo for the most gentle shower time"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">V\u00e9ritable moment pour soi au c\u0153ur de notre routine bien-\u00eatre, la douche nous permet de nous d\u00e9faire de nos tensions et des petits tracas du quotidien. Et pour profiter au mieux de cet instant apaisant, choisir m\u00e9ticuleusement ses produits est une \u00e9tape cl\u00e9. Standards a donc s\u00e9lectionn\u00e9 pour vous, ce duo \u00e0 tester sans plus tarder !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La Ros\u00e9e &#8211; Huile de douche lavante, 15,90\u20ac<\/strong><br>C&#8217;est par sa l\u00e9g\u00e8re odeur abricot\u00e9e que l&#8217;huile de douche La Ros\u00e9e gagnera votre coeur de mani\u00e8re instantan\u00e9e. Compos\u00e9e en grande partie d&#8217;huile de graine de tournesol bio, cette huile lavante vegan hydrate en profondeur, et sur la dur\u00e9e, votre peau tout en la lavant d\u00e9licatement. Id\u00e9ale pour les peaux s\u00e8ches, sa texture huileuse se transforme en une mousse onctueuse au contact de l&#8217;eau pour un lavage en douceur sous le signe de la d\u00e9licatesse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>KORRES &#8211; Gel douche eau de noix de coco, 7,90\u20ac<\/strong><br>Si votre coeur balance mais que la formule gel douche reste votre favorite, celui \u00e0 l&#8217;eau de noix de coco par KORRES n&#8217;attend que vous ! Son pH neutre vous permet un lavage sans agressivit\u00e9 qui pr\u00e9servera l&#8217;hydratation de votre peau notamment gr\u00e2ce \u00e0 sa formule \u00e0 base d&#8217;alo\u00e8s. Le petit plus ? Une odeur de noix de coco \u00e0 tomber qui vous enveloppe m\u00eame une fois sorti de la douche !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>V\u00e9ritable moment pour soi au c\u0153ur de notre routine bien-\u00eatre, la douche nous permet de nous d\u00e9faire de nos tensions et des petits tracas du quotidien. Et pour profiter au mieux de cet instant apaisant, choisir m\u00e9ticuleusement ses produits est une \u00e9tape cl\u00e9. Standards a donc s\u00e9lectionn\u00e9 pour vous, ce duo \u00e0 tester sans plus [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12000,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[43],"tags":[],"class_list":["post-12002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beauty"],"jetpack_featured_media_url":"https:\/\/standardsmagazine.com\/wp-content\/uploads\/2022\/08\/geldouche_standardsmagazine.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/standardsmagazine.com\/en\/wp-json\/wp\/v2\/posts\/12002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/standardsmagazine.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/standardsmagazine.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/standardsmagazine.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/standardsmagazine.com\/en\/wp-json\/wp\/v2\/comments?post=12002"}],"version-history":[{"count":4,"href":"https:\/\/standardsmagazine.com\/en\/wp-json\/wp\/v2\/posts\/12002\/revisions"}],"predecessor-version":[{"id":12018,"href":"https:\/\/standardsmagazine.com\/en\/wp-json\/wp\/v2\/posts\/12002\/revisions\/12018"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/standardsmagazine.com\/en\/wp-json\/wp\/v2\/media\/12000"}],"wp:attachment":[{"href":"https:\/\/standardsmagazine.com\/en\/wp-json\/wp\/v2\/media?parent=12002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/standardsmagazine.com\/en\/wp-json\/wp\/v2\/categories?post=12002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/standardsmagazine.com\/en\/wp-json\/wp\/v2\/tags?post=12002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}